{"id":2484,"date":"2016-03-14T11:38:00","date_gmt":"2016-03-14T10:38:00","guid":{"rendered":"https:\/\/www.fleckenstein.fr\/?p=2484&#038;lang=de"},"modified":"2016-04-04T14:44:04","modified_gmt":"2016-04-04T13:44:04","slug":"1720","status":"publish","type":"post","link":"https:\/\/www.fleckenstein.fr\/de\/1720\/","title":{"rendered":"1720"},"content":{"rendered":"<p>Tod des letzten Freiherren von Fleckenstein, Henri-Jacques, ohne m\u00e4nnlichen Erben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tod des letzten Freiherren von Fleckenstein, Henri-Jacques, ohne m\u00e4nnlichen Erben.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-2484","post","type-post","status-publish","format-standard","hentry","category-geschichtliche-chronik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1720 - Ch\u00e2teau de Fleckenstein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleckenstein.fr\/1720\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1720 - Ch\u00e2teau de Fleckenstein\" \/>\n<meta property=\"og:description\" content=\"Tod des letzten Freiherren von Fleckenstein, Henri-Jacques, ohne m\u00e4nnlichen Erben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleckenstein.fr\/1720\/\" \/>\n<meta property=\"og:site_name\" content=\"Ch\u00e2teau de Fleckenstein\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-14T10:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-04T13:44:04+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/#\\\/schema\\\/person\\\/6c99c997263f3e866488f1fb860d2fde\"},\"headline\":\"1720\",\"datePublished\":\"2016-03-14T10:38:00+00:00\",\"dateModified\":\"2016-04-04T13:44:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/\"},\"wordCount\":11,\"articleSection\":[\"Geschichtliche Chronik\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/\",\"url\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/\",\"name\":\"1720 - Ch\u00e2teau de Fleckenstein\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/#website\"},\"datePublished\":\"2016-03-14T10:38:00+00:00\",\"dateModified\":\"2016-04-04T13:44:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/#\\\/schema\\\/person\\\/6c99c997263f3e866488f1fb860d2fde\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/1720\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1720\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/\",\"name\":\"Ch\u00e2teau de Fleckenstein\",\"description\":\"Entdecken Sie die Burg Fleckenstein in Frankreich nahe der deutschen Grenze\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/#\\\/schema\\\/person\\\/6c99c997263f3e866488f1fb860d2fde\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7ef41349801aca16a728dc63f01b2ad93f82fb81ff89de66432bbd8484b3813?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7ef41349801aca16a728dc63f01b2ad93f82fb81ff89de66432bbd8484b3813?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7ef41349801aca16a728dc63f01b2ad93f82fb81ff89de66432bbd8484b3813?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.fleckenstein.fr\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1720 - Ch\u00e2teau de Fleckenstein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleckenstein.fr\/1720\/","og_locale":"de_DE","og_type":"article","og_title":"1720 - Ch\u00e2teau de Fleckenstein","og_description":"Tod des letzten Freiherren von Fleckenstein, Henri-Jacques, ohne m\u00e4nnlichen Erben.","og_url":"https:\/\/www.fleckenstein.fr\/1720\/","og_site_name":"Ch\u00e2teau de Fleckenstein","article_published_time":"2016-03-14T10:38:00+00:00","article_modified_time":"2016-04-04T13:44:04+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fleckenstein.fr\/1720\/#article","isPartOf":{"@id":"https:\/\/www.fleckenstein.fr\/1720\/"},"author":{"name":"admin","@id":"https:\/\/www.fleckenstein.fr\/de\/#\/schema\/person\/6c99c997263f3e866488f1fb860d2fde"},"headline":"1720","datePublished":"2016-03-14T10:38:00+00:00","dateModified":"2016-04-04T13:44:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fleckenstein.fr\/1720\/"},"wordCount":11,"articleSection":["Geschichtliche Chronik"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.fleckenstein.fr\/1720\/","url":"https:\/\/www.fleckenstein.fr\/1720\/","name":"1720 - Ch\u00e2teau de Fleckenstein","isPartOf":{"@id":"https:\/\/www.fleckenstein.fr\/de\/#website"},"datePublished":"2016-03-14T10:38:00+00:00","dateModified":"2016-04-04T13:44:04+00:00","author":{"@id":"https:\/\/www.fleckenstein.fr\/de\/#\/schema\/person\/6c99c997263f3e866488f1fb860d2fde"},"breadcrumb":{"@id":"https:\/\/www.fleckenstein.fr\/1720\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleckenstein.fr\/1720\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleckenstein.fr\/1720\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fleckenstein.fr\/de\/"},{"@type":"ListItem","position":2,"name":"1720"}]},{"@type":"WebSite","@id":"https:\/\/www.fleckenstein.fr\/de\/#website","url":"https:\/\/www.fleckenstein.fr\/de\/","name":"Ch\u00e2teau de Fleckenstein","description":"Entdecken Sie die Burg Fleckenstein in Frankreich nahe der deutschen Grenze","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleckenstein.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.fleckenstein.fr\/de\/#\/schema\/person\/6c99c997263f3e866488f1fb860d2fde","name":"admin","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/c7ef41349801aca16a728dc63f01b2ad93f82fb81ff89de66432bbd8484b3813?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7ef41349801aca16a728dc63f01b2ad93f82fb81ff89de66432bbd8484b3813?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7ef41349801aca16a728dc63f01b2ad93f82fb81ff89de66432bbd8484b3813?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.fleckenstein.fr\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/posts\/2484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/comments?post=2484"}],"version-history":[{"count":1,"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/posts\/2484\/revisions"}],"predecessor-version":[{"id":2485,"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/posts\/2484\/revisions\/2485"}],"wp:attachment":[{"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/media?parent=2484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/categories?post=2484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fleckenstein.fr\/de\/wp-json\/wp\/v2\/tags?post=2484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}